{"id":19069,"date":"2023-05-18T12:11:07","date_gmt":"2023-05-18T10:11:07","guid":{"rendered":"https:\/\/www.reflexangelo.com\/?page_id=19069"},"modified":"2023-05-18T12:11:07","modified_gmt":"2023-05-18T10:11:07","slug":"materials","status":"publish","type":"page","link":"https:\/\/www.reflexangelo.com\/en\/materials\/","title":{"rendered":"Materials"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column]<div class=\"banner-titolo \"   > <div class=\"banner-titolo-inn\"  style=\"background-image: url(https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2022\/10\/legno.jpg)\"  > <div class=\"ombra\"><\/div><div class=\"container\"   > <div class=\"banner-titolo-inside\"  > <div class=\"spacer\"><\/div><div class=\"banner-titolo-text\"  > <h1 class=\"titolo colore-bianco\"><\/p>\n<p style=\"text-align: center;\">Materials<\/p>\n<p><\/h1><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column]    <div class=\"lista-materiali-cont \">\n        <div class=\"d-none\">\n            <div class=\"lista-categorie\">{\"1525\":{\"id\":1525,\"nome\":\"Glass\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/vetro.jpg\",\"figli\":[{\"id\":1553,\"nome\":\"Lacquered glass\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0035_vetri-lucidi.jpg\"},{\"id\":1555,\"nome\":\"Decor glass\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0033_decor.jpg\"},{\"id\":1557,\"nome\":\"Solid striped glass\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0031_vetro-massiccio-rigato.jpg\"},{\"id\":1559,\"nome\":\"Blown glass\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0030_vetro-soffiato.jpg\"},{\"id\":1558,\"nome\":\"Special glass\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0028_murano.jpg\"},{\"id\":1561,\"nome\":\"MarmoReflex\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0027_vm.jpg\"},{\"id\":1562,\"nome\":\"LegnoReflex\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0026_vl.jpg\"},{\"id\":1563,\"nome\":\"Gradient glass\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0025_sfumati.jpg\"}]},\"1524\":{\"id\":1524,\"nome\":\"Wood\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/legno.jpg\",\"figli\":[{\"id\":1548,\"nome\":\"Wood Essences\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0024_legni.jpg\"},{\"id\":1546,\"nome\":\"Glossy lacquered wood\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0035_vetri-lucidi.jpg\"}]},\"1551\":{\"id\":1551,\"nome\":\"Special finishes\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/finiture-speciali.jpg\",\"figli\":[{\"id\":1552,\"nome\":\"Special finishes\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0023_fin-speciali.jpg\"}]},\"1523\":{\"id\":1523,\"nome\":\"Leather\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/pelle.jpg\",\"figli\":[{\"id\":1526,\"nome\":\"Categoria C\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0021_cat-C.jpg\"},{\"id\":1527,\"nome\":\"Colorata\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0020_colorata.jpg\"},{\"id\":1542,\"nome\":\"Naturale\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0018_naturale.jpg\"},{\"id\":1543,\"nome\":\"Nabuk\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0019_nabuk.jpg\"},{\"id\":1615,\"nome\":\"Eco Leather Essential Outdoor \",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/ecopelle-essential.png\"},{\"id\":1610,\"nome\":\"Eco Leather Teraskin Outdoor \",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/teraskinecopelle.png\"}]},\"1518\":{\"id\":1518,\"nome\":\"Fabric\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Tessuto.jpg\",\"figli\":[{\"id\":1791,\"nome\":\"Aura\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Pagina-Aura-scaled.jpg\"},{\"id\":1793,\"nome\":\"Super Praga\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Pagina-Praga-scaled.jpg\"},{\"id\":1520,\"nome\":\"Super Via Bagutta\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0016_via-bagutta.jpg\"},{\"id\":1792,\"nome\":\"Super Vienna\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Pagina-Vienna-scaled.jpg\"},{\"id\":1521,\"nome\":\"Extra Amsterdam\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0015_amsterdam.jpg\"},{\"id\":1522,\"nome\":\"Extra Dublino\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0014_dublino.jpg\"},{\"id\":1604,\"nome\":\"Extra Mayfair\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2222_Tavola-disegno-1.png\"},{\"id\":1606,\"nome\":\"Extra Indoor\\\/Outdoor Positano\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Positano.jpg\"},{\"id\":1603,\"nome\":\"Luxury Aspen\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/aspen.png\"},{\"id\":1532,\"nome\":\"Luxury Brook Street\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/2222_Tavola-disegno-1.jpg\"},{\"id\":1533,\"nome\":\"Luxury Firenze\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0008_firenze.jpg\"},{\"id\":1788,\"nome\":\"Luxury Monaco\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Pagina-Monaco-scaled.jpg\"},{\"id\":1605,\"nome\":\"Luxury Indoor\\\/Outdoor Amalfi\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Amalfi.jpg\"},{\"id\":1534,\"nome\":\"Luxury Indoor\\\/Outdoor Milano\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0007_milano.jpg\"},{\"id\":1790,\"nome\":\"Luxury Indoor\\\/Outdoor Mykonos\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Pagina-Mykonos-scaled.jpg\"},{\"id\":1789,\"nome\":\"Luxury Indoor\\\/Outdoor Santorini\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Pagina-Santorini-scaled.jpg\"},{\"id\":1573,\"nome\":\"Luxury Roma\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cover_roma.jpg\"},{\"id\":1536,\"nome\":\"Luxury Venezia\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0005_venezia.jpg\"},{\"id\":1602,\"nome\":\"Luxury Verona\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/verona-01.png\"},{\"id\":1538,\"nome\":\"Decorative Millefiori\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0003_millefiori.jpg\"}]},\"1794\":{\"id\":1794,\"nome\":\"Fabric outdoor\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Tessuto-outdoor.jpg\",\"figli\":[{\"id\":1799,\"nome\":\"Extra Indoor\\\/Outdoor Positano\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Positano.jpg\"},{\"id\":1795,\"nome\":\"Luxury Indoor\\\/Outdoor Amalfi\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Amalfi.jpg\"},{\"id\":1796,\"nome\":\"Luxury Indoor\\\/Outdoor Milano\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0007_milano.jpg\"},{\"id\":1797,\"nome\":\"Luxury Indoor\\\/Outdoor Mykonos\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Pagina-Mykonos-scaled.jpg\"},{\"id\":1798,\"nome\":\"Luxury Indoor\\\/Outdoor Santorini\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Pagina-Santorini-scaled.jpg\"}]},\"1544\":{\"id\":1544,\"nome\":\"Quilt\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Trapunte.jpg\",\"figli\":[{\"id\":1545,\"nome\":\"Quilt\",\"img\":\"https:\\\/\\\/www.reflexangelo.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/0000_trapunte.jpg\"}]}}<\/div>\n        <\/div>\n\n        <div class=\"lista-materiali-select d-block d-sm-none\">\n            <div class=\"blocco-select\">\n                <div class=\"cat-principale-cont select-cont\">\n                    <select class=\"cat-principale\" name=\"cat-principale\">\n                                                    <option value=\"1525\">Glass<\/option>                            <option value=\"1524\">Wood<\/option>                            <option value=\"1551\">Special finishes<\/option>                            <option value=\"1523\">Leather<\/option>                            <option value=\"1518\">Fabric<\/option>                            <option value=\"1794\">Fabric outdoor<\/option>                            <option value=\"1544\">Quilt<\/option>                    <\/select>\n                <\/div>\n                <div class=\"cat-secondaria-cont select-cont\">\n                    <select class=\"cat-secondaria\" name=\"cat-secondaria\"><\/select>\n                <\/div>\n            <\/div>\n\n        <\/div>\n\n\n        <div class=\"lista-materiali-images d-none d-sm-block\">\n\n\n            <div class=\"main-categorie\">\n                <div class=\"row spazio-standard\">\n                                            <div class=\"col-md-4 col-sm-4 col-6\">\n                            <a href=\"javascript:void(0);\" class=\"select-img select-main-categoria\"\n                               data-value=\"1525\">\n                                <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/vetro.jpg\" class=\"img-fluid\"\/>\n                                <h4 class=\"titolo\">Glass<\/h4>\n                            <\/a>\n                        <\/div>\n                                                <div class=\"col-md-4 col-sm-4 col-6\">\n                            <a href=\"javascript:void(0);\" class=\"select-img select-main-categoria\"\n                               data-value=\"1524\">\n                                <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/legno.jpg\" class=\"img-fluid\"\/>\n                                <h4 class=\"titolo\">Wood<\/h4>\n                            <\/a>\n                        <\/div>\n                                                <div class=\"col-md-4 col-sm-4 col-6\">\n                            <a href=\"javascript:void(0);\" class=\"select-img select-main-categoria\"\n                               data-value=\"1551\">\n                                <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/finiture-speciali.jpg\" class=\"img-fluid\"\/>\n                                <h4 class=\"titolo\">Special finishes<\/h4>\n                            <\/a>\n                        <\/div>\n                                                <div class=\"col-md-4 col-sm-4 col-6\">\n                            <a href=\"javascript:void(0);\" class=\"select-img select-main-categoria\"\n                               data-value=\"1523\">\n                                <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/pelle.jpg\" class=\"img-fluid\"\/>\n                                <h4 class=\"titolo\">Leather<\/h4>\n                            <\/a>\n                        <\/div>\n                                                <div class=\"col-md-4 col-sm-4 col-6\">\n                            <a href=\"javascript:void(0);\" class=\"select-img select-main-categoria\"\n                               data-value=\"1518\">\n                                <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/Tessuto.jpg\" class=\"img-fluid\"\/>\n                                <h4 class=\"titolo\">Fabric<\/h4>\n                            <\/a>\n                        <\/div>\n                                                <div class=\"col-md-4 col-sm-4 col-6\">\n                            <a href=\"javascript:void(0);\" class=\"select-img select-main-categoria\"\n                               data-value=\"1794\">\n                                <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/Tessuto-outdoor.jpg\" class=\"img-fluid\"\/>\n                                <h4 class=\"titolo\">Fabric outdoor<\/h4>\n                            <\/a>\n                        <\/div>\n                                                <div class=\"col-md-4 col-sm-4 col-6\">\n                            <a href=\"javascript:void(0);\" class=\"select-img select-main-categoria\"\n                               data-value=\"1544\">\n                                <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/Trapunte.jpg\" class=\"img-fluid\"\/>\n                                <h4 class=\"titolo\">Quilt<\/h4>\n                            <\/a>\n                        <\/div>\n                                        <\/div>\n            <\/div>\n\n\n            <div class=\"figlie-categorie\">\n\n                <div class=\"singola-figlia\" data-padre=\"1525\"><div class=\"row spazio-standard\">                            <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1553\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0035_vetri-lucidi.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Lacquered glass<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1555\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0033_decor.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Decor glass<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1557\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0031_vetro-massiccio-rigato.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Solid striped glass<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1559\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0030_vetro-soffiato.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Blown glass<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1558\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0028_murano.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Special glass<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1561\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0027_vm.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">MarmoReflex<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1562\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0026_vl.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">LegnoReflex<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1563\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0025_sfumati.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Gradient glass<\/h4>\n                                <\/a>\n                            <\/div>\n                            <\/div><\/div><div class=\"singola-figlia\" data-padre=\"1524\"><div class=\"row spazio-standard\">                            <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1548\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0024_legni.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Wood Essences<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1546\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0035_vetri-lucidi.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Glossy lacquered wood<\/h4>\n                                <\/a>\n                            <\/div>\n                            <\/div><\/div><div class=\"singola-figlia\" data-padre=\"1551\"><div class=\"row spazio-standard\">                            <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1552\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0023_fin-speciali.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Special finishes<\/h4>\n                                <\/a>\n                            <\/div>\n                            <\/div><\/div><div class=\"singola-figlia\" data-padre=\"1523\"><div class=\"row spazio-standard\">                            <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1526\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0021_cat-C.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Categoria C<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1527\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0020_colorata.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Colorata<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1542\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0018_naturale.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Naturale<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1543\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0019_nabuk.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Nabuk<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1615\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2024\/08\/ecopelle-essential.png\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Eco Leather Essential Outdoor <\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1610\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2024\/06\/teraskinecopelle.png\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Eco Leather Teraskin Outdoor <\/h4>\n                                <\/a>\n                            <\/div>\n                            <\/div><\/div><div class=\"singola-figlia\" data-padre=\"1518\"><div class=\"row spazio-standard\">                            <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1791\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/Pagina-Aura-scaled.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Aura<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1793\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/Pagina-Praga-scaled.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Super Praga<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1520\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0016_via-bagutta.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Super Via Bagutta<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1792\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/Pagina-Vienna-scaled.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Super Vienna<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1521\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0015_amsterdam.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Extra Amsterdam<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1522\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0014_dublino.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Extra Dublino<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1604\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2024\/05\/2222_Tavola-disegno-1.png\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Extra Mayfair<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1606\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2024\/05\/Positano.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Extra Indoor\/Outdoor Positano<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1603\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2024\/05\/aspen.png\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Aspen<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1532\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/10\/2222_Tavola-disegno-1.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Brook Street<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1533\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0008_firenze.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Firenze<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1788\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/Pagina-Monaco-scaled.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Monaco<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1605\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2024\/05\/Amalfi.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Indoor\/Outdoor Amalfi<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1534\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0007_milano.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Indoor\/Outdoor Milano<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1790\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/Pagina-Mykonos-scaled.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Indoor\/Outdoor Mykonos<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1789\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/Pagina-Santorini-scaled.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Indoor\/Outdoor Santorini<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1573\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/06\/cover_roma.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Roma<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1536\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0005_venezia.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Venezia<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1602\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2024\/05\/verona-01.png\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Verona<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1538\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0003_millefiori.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Decorative Millefiori<\/h4>\n                                <\/a>\n                            <\/div>\n                            <\/div><\/div><div class=\"singola-figlia\" data-padre=\"1794\"><div class=\"row spazio-standard\">                            <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1799\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2024\/05\/Positano.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Extra Indoor\/Outdoor Positano<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1795\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2024\/05\/Amalfi.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Indoor\/Outdoor Amalfi<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1796\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0007_milano.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Indoor\/Outdoor Milano<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1797\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/Pagina-Mykonos-scaled.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Indoor\/Outdoor Mykonos<\/h4>\n                                <\/a>\n                            <\/div>\n                                                        <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1798\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2026\/05\/Pagina-Santorini-scaled.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Luxury Indoor\/Outdoor Santorini<\/h4>\n                                <\/a>\n                            <\/div>\n                            <\/div><\/div><div class=\"singola-figlia\" data-padre=\"1544\"><div class=\"row spazio-standard\">                            <div class=\"col-md-3 col-sm-4 col-6\">\n                                <a href=\"javascript:void(0);\" class=\"select-img select-figlio-categoria\"\n                                   data-value=\"1545\">\n                                                                          <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/uploads\/2023\/05\/0000_trapunte.jpg\" class=\"img-fluid\"\/>\n                                    \n                                    <h4 class=\"titolo\">Quilt<\/h4>\n                                <\/a>\n                            <\/div>\n                            <\/div><\/div>            <\/div>\n\n\n        <\/div>\n\n\n        <div class=\"risultati\">\n            <div class=\"risultati-inner\">\n                <div class=\"risultati-alpine\" id=\"listamaterialidom\" x-data=\"listamateriali\">\n                    <div class=\"row spazio-standard\">\n                        <template x-for=\"(materiale, index) in dati\">\n                            <div class=\"col-md-3 col-sm-4 col-6\">\n                                <div class=\"singolo-risultato \" :data-idprod=\"materiale.id\">\n                                    <div class=\"materiale-image\">\n                                        <img x-if=\"materiale.foto_normale\" :src=\"materiale.foto_normale\"\/>\n                                    <\/div>    \n                                    <h4 class=\"titolo\" x-text=\"materiale.nome\"><\/h4>\n                                <\/div>\n\n                            <\/div>\n                        <\/template>\n\n                    <\/div>\n                    <div class=\"loader text-center\" x-show=\"isLoading\">\n                        <img decoding=\"async\" src=\"https:\/\/www.reflexangelo.com\/wp-content\/themes\/reflex\/includes\/shortcodes\/lista_materiali\/images\/loader.gif\" \/>\n                    <\/div>\n\n\n                    <div class=\"d-none\">\n                        <div class=\"debug\">\n                            DEBUG\n                            <button\n                                    id=\"syncdata\"\n                                    @click=\"syncData\"\n                            >\n                                Click to post\n                            <\/button>\n                        <\/div>\n                    <\/div>\n\n                <\/div>\n            <\/div>\n\n\n        <\/div>\n\n    <\/div>\n    [\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-19069","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Materials - Reflex Angelo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reflexangelo.com\/en\/materials\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Materials - Reflex Angelo\" \/>\n<meta property=\"og:description\" content=\"[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reflexangelo.com\/en\/materials\/\" \/>\n<meta property=\"og:site_name\" content=\"Reflex Angelo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reflexangelo.com\\\/en\\\/materials\\\/\",\"url\":\"https:\\\/\\\/www.reflexangelo.com\\\/en\\\/materials\\\/\",\"name\":\"Materials - Reflex Angelo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reflexangelo.com\\\/en\\\/#website\"},\"datePublished\":\"2023-05-18T10:11:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reflexangelo.com\\\/en\\\/materials\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reflexangelo.com\\\/en\\\/materials\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reflexangelo.com\\\/en\\\/materials\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reflexangelo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Materials\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reflexangelo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.reflexangelo.com\\\/en\\\/\",\"name\":\"Reflex Angelo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reflexangelo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Materials - Reflex Angelo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reflexangelo.com\/en\/materials\/","og_locale":"en_US","og_type":"article","og_title":"Materials - Reflex Angelo","og_description":"[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]","og_url":"https:\/\/www.reflexangelo.com\/en\/materials\/","og_site_name":"Reflex Angelo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.reflexangelo.com\/en\/materials\/","url":"https:\/\/www.reflexangelo.com\/en\/materials\/","name":"Materials - Reflex Angelo","isPartOf":{"@id":"https:\/\/www.reflexangelo.com\/en\/#website"},"datePublished":"2023-05-18T10:11:07+00:00","breadcrumb":{"@id":"https:\/\/www.reflexangelo.com\/en\/materials\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reflexangelo.com\/en\/materials\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.reflexangelo.com\/en\/materials\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reflexangelo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Materials"}]},{"@type":"WebSite","@id":"https:\/\/www.reflexangelo.com\/en\/#website","url":"https:\/\/www.reflexangelo.com\/en\/","name":"Reflex Angelo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reflexangelo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.reflexangelo.com\/en\/wp-json\/wp\/v2\/pages\/19069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reflexangelo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.reflexangelo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.reflexangelo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reflexangelo.com\/en\/wp-json\/wp\/v2\/comments?post=19069"}],"version-history":[{"count":1,"href":"https:\/\/www.reflexangelo.com\/en\/wp-json\/wp\/v2\/pages\/19069\/revisions"}],"predecessor-version":[{"id":19070,"href":"https:\/\/www.reflexangelo.com\/en\/wp-json\/wp\/v2\/pages\/19069\/revisions\/19070"}],"wp:attachment":[{"href":"https:\/\/www.reflexangelo.com\/en\/wp-json\/wp\/v2\/media?parent=19069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}